{"id":379,"count":2,"description":"<p>El <strong>Ogur Sazi<\/strong> es un la\u00fad anatolio contempor\u00e1neo de seis cuerdas ideado por el m\u00fasico turco <strong>Erkan Ogur<\/strong>, y nuestra colecci\u00f3n Tapadum re\u00fane ejemplares hechos a mano para los m\u00fasicos atra\u00eddos por su voz inventiva. Entre los dise\u00f1os m\u00e1s recientes de nuestra familia de <a href=\"\/es\/categoria-producto\/instrumentos-de-cuerda\/\">instrumentos de cuerda<\/a>, es af\u00edn en forma al <a href=\"\/es\/categoria-producto\/instrumentos-de-cuerda\/baglama-saz-es\/\">baglama y saz<\/a> \u2014 pero el Ogur Sazi dispone cada una de sus seis cuerdas de forma individual, como una guitarra, en lugar de los \u00f3rdenes dobles del saz tradicional.<\/p>\n\n<p>Este simple cambio abre una gama de acordes mucho m\u00e1s amplia y una paleta tonal m\u00e1s rica. El Ogur Sazi se toca normalmente sin p\u00faa, con t\u00e9cnica de fingerstyle y arpegio, para que cada nota suene con claridad. Erkan Ogur ide\u00f3 su propio sistema de afinaci\u00f3n no tradicional y construy\u00f3 el instrumento en varias configuraciones, incluidas variantes de nueve cuerdas de una fila y doce cuerdas de doble fila. Muchos de nuestros modelos se realizan como <em>kopuz<\/em>, combinando la caja anatolia con modernas clavijas de afinaci\u00f3n de estilo guitarra.<\/p>\n\n<p>Nuestros modelos de Ogur Sazi suelen estar hechos a mano con cajas de madera de enebro para una resonancia c\u00e1lida, m\u00e1stiles de caoba para estabilidad y diapasones de nogal turco para una superficie de juego suave y duradera. Cada instrumento se ajusta y revisa con nuestro especialista en instrumentos de cuerda <a href=\"\/es\/team\/sertan-sarioglu\/\">Sertan Sarioglu<\/a> antes de partir desde nuestro showroom de Brisighella, Italia.<\/p>\n\n<p>Explora nuestra colecci\u00f3n de Ogur Sazi hechos a mano y descubre un instrumento que une la tradici\u00f3n anatolia con un dise\u00f1o inventivo. Env\u00edo internacional y devoluci\u00f3n en 15 d\u00edas.<\/p>","link":"https:\/\/tapadum.com\/es\/categoria-producto\/instrumentos-de-cuerda\/ogur-sazi-es\/","name":"Ogur Sazi","slug":"ogur-sazi-es","taxonomy":"product_cat","parent":346,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/tapadum.com\/es\/wp-json\/wp\/v2\/product_cat\/379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tapadum.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/tapadum.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/tapadum.com\/es\/wp-json\/wp\/v2\/product_cat\/346"}],"wp:post_type":[{"href":"https:\/\/tapadum.com\/es\/wp-json\/wp\/v2\/product?product_cat=379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}